{"id":10156,"date":"2020-03-27T07:00:40","date_gmt":"2020-03-27T06:00:40","guid":{"rendered":"https:\/\/jennyisbaking.com\/?p=10156"},"modified":"2020-05-12T19:12:36","modified_gmt":"2020-05-12T17:12:36","slug":"creamy-cheesecake-with-rhubarb-and-strawberry-sauce","status":"publish","type":"post","link":"https:\/\/jennyisbaking.com\/de\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/","title":{"rendered":"Der cremigste Rhabarber-Erdbeer-K\u00e4sekuchen"},"content":{"rendered":"<p>[Anzeige|Gewinnspiel] Endlich war es da, das so liebevoll gemachte Backbuch <a href=\"https:\/\/www.tchibo.de\/buch-fruehlingsbacken-p400148139.html\" target=\"_blank\" rel=\"noopener noreferrer\">&#8222;Fr\u00fchlingsbacken&#8220;<\/a> von Emma in Zusammenarbeit mit Tchibo. <del>Das verlose ich hier gleich zwei Mal, wenn du am Giveaway teilnehmen willst, schau mal unter dem Rezept<\/del>! Emma hatte bereits auf <a href=\"https:\/\/www.instagram.com\/emmaslieblingsstuecke\/\" target=\"_blank\" rel=\"noopener noreferrer\">Instagram in ihren Stories<\/a> (jetzt auch in den Highlights) immer wieder von diesem B\u00fcchlein erz\u00e4hlt und es klang so ganz nach meinem Herzen, ganz viel Rhabarber, ganz viel Erdbeer, ein bisschen Himbeere und Zitrone. Egal, ob im schnellen Kuchen, pomp\u00f6sen Torten, einer schlichten Tarte oder im Kleingeb\u00e4ck, ich bin mir sicher, dass jeder von euch hier f\u00fcndig wird. Das Buch kam also per Post an und ich schaffte es gerade Mal bis zum ersten Rezept. Denn da sprang mir dieser umwerfend leckere K\u00e4sekuchen sofort ins Auge: mega cremig mit einer Rhabarber- und Erdbeerso\u00dfe als absolutes i-T\u00fcpfelchen.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07661.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"10157\" data-permalink=\"https:\/\/jennyisbaking.com\/de\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/dsc07661-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07661.jpg?fit=534%2C801&amp;ssl=1\" data-orig-size=\"534,801\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.5&quot;,&quot;credit&quot;:&quot;Jennifer Warkentin&quot;,&quot;camera&quot;:&quot;ILCE-7&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1584725532&quot;,&quot;copyright&quot;:&quot;Jennifer Warkentin&quot;,&quot;focal_length&quot;:&quot;50&quot;,&quot;iso&quot;:&quot;640&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Das Backbuch Fr\u00fchlingsbacken von Tchibo\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07661.jpg?fit=534%2C801&amp;ssl=1\" class=\"aligncenter size-full wp-image-10157\" src=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07661.jpg?resize=534%2C801&#038;ssl=1\" alt=\"Das Backbuch Fr\u00fchlingsbacken von Tchibo\" width=\"534\" height=\"801\" srcset=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07661.jpg?w=534&amp;ssl=1 534w, https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07661.jpg?resize=200%2C300&amp;ssl=1 200w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" \/><\/a><\/p>\n<p><!--more-->K\u00e4sekuchen ist ja eher nicht so meins, ich wei\u00df, ich wei\u00df. Tut mir leid, aber ich bin einfach nicht so sehr daf\u00fcr zu haben, sorry. Aber genau deshalb war ich so begeistert von diesem <a href=\"https:\/\/www.tchibo.de\/buch-fruehlingsbacken-p400148139.html\" target=\"_blank\" rel=\"noopener noreferrer\">Backbuch<\/a> und wollte es unbedingt haben, denn hier wird es sehr fruchtig. Hier kommen genau die frischen Zutaten zum Einsatz, die ich so gerne mag. Und dieses Bild, das war einfach so umwerfend sch\u00f6n, da dachte ich mir, OK, gibst du mal K\u00e4sekuchen nochmal eine Chance. Mein bisheriger Liebling ist dieser <a href=\"https:\/\/jennyisbaking.com\/de\/2019\/05\/03\/creamy-german-cheesecake-with-strawberries\/\" target=\"_blank\" rel=\"noopener noreferrer\">K\u00e4sekuchen<\/a>, ich hatte also einen hohen Anspruch. Schnell noch dem Gatten gezeigt, der nickte eifrig, es war also geritzt.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07705.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"10159\" data-permalink=\"https:\/\/jennyisbaking.com\/de\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/dsc07705\/\" data-orig-file=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07705.jpg?fit=534%2C801&amp;ssl=1\" data-orig-size=\"534,801\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;Jennifer Warkentin&quot;,&quot;camera&quot;:&quot;ILCE-7&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1584727503&quot;,&quot;copyright&quot;:&quot;Jennifer Warkentin&quot;,&quot;focal_length&quot;:&quot;50&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Cremiger K\u00e4sekuchen mit Rhabarber- und Erdbeerso\u00dfe\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07705.jpg?fit=534%2C801&amp;ssl=1\" class=\"aligncenter size-full wp-image-10159\" src=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07705.jpg?resize=534%2C801&#038;ssl=1\" alt=\"Cremiger K\u00e4sekuchen mit Rhabarber- und Erdbeerso\u00dfe\" width=\"534\" height=\"801\" srcset=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07705.jpg?w=534&amp;ssl=1 534w, https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07705.jpg?resize=200%2C300&amp;ssl=1 200w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" \/><\/a>Und weil man bei K\u00e4sekuchen leider immer super lange warten muss, riss mir irgendwann der Geduldsfaden, vom K\u00fchlschrank ging es kurzerhand einfach mal ins Gefrierfach und dann musste ich ihn ganz schnell probieren. Oh, ich glaube, dieser K\u00e4sekuchen hat mich bekehrt, der ist wirklich sowas von cremig und lecker, unfassbar gut! Und wenn mein laktoseintoleranter Ehemann gleich zwei St\u00fccke vertilgt, auf die Gefahr, dass es ihm danach nicht so gut geht, das will was hei\u00dfen. Bei Familie Jenny is baking war die Freude gro\u00df, 100 Punkte, den machen wir auf jeden Fall wieder.<\/p>\n<p>Ich w\u00e4re aber nicht Backbloggerin, wenn ich nicht doch ein paar \u00c4nderungen am Rezept vorgenommen h\u00e4tte. Hier also meine \u00c4nderungen und meine Tipps zum Thema K\u00e4sekuchen:<\/p>\n<ul>\n<li>Emma, sorry, hier gibt es Schmand nur in 200 Gramm Bechern, daf\u00fcr Quark in\u00a0 der 250 Gramm Packung, also habe ich das mal kurzerhand einfach ausgetauscht.<\/li>\n<li>Bei K\u00e4sekuchen solltest du deinen Mixer sch\u00f6n in der Schublade lassen, da reicht ein Schneebesen. Denn die Grundidee ist, dass man m\u00f6glichst wenig Luft einschl\u00e4gt. Je weniger Luft eingeschlagen wird, desto geringer ist auch die Chance, dass der K\u00e4sekuchen hinterher wieder zusammensackt, wenn die Luft entweicht. Immer also sch\u00f6n sachte und lieber weniger verr\u00fchren.<\/li>\n<li>Deshalb habe ich auch die Reihenfolge der Zutaten ge\u00e4ndert. Eier verklumpen Speisest\u00e4rke, deshalb gebe ich sie erst ganz am Ende vorsichtig dazu und l\u00f6se lieber die Speisest\u00e4rke zu Beginn in der Milch und Sahne auf.<\/li>\n<li>K\u00e4sekuchen soll man normalerweise bei ca. 160 Grad backen, damit die Eier stocken und eben nicht so viel Triebkraft entwickeln (deshalb wird <a href=\"https:\/\/jennyisbaking.com\/de\/2019\/04\/09\/twelve-tips-for-perfect-sponge-batter\/\" target=\"_blank\" rel=\"noopener noreferrer\">Biskuit<\/a> auch mit eher hohen Temperaturen gebacken). Emma gibt 180 Grad an, was ziemlich hoch f\u00fcr K\u00e4sekuchen ist, deshalb habe ich die goldene Mitte gew\u00e4hlt und 170 Grad genommen.<\/li>\n<li>K\u00e4sekuchen am besten etappenweise ausk\u00fchlen, erst im ausgeschalteten Ofen, dann bei Raumtemperatur und dann erst in den K\u00fchlschrank, so vermeidest du Risse und dass er zusammenf\u00e4llt. Falls du jedoch auch so ungeduldig bist wie ich, haust du ihn irgendwann kurz ins Gefrierfach, denn schneiden kann man K\u00e4sekuchen tats\u00e4chlich am besten, wenn er \u00fcber Nacht k\u00fchlen konnte.\u00a0 Aber eine Trumpfkarte gibt es bei diesem Kuchen: Risse sieht man sowieso nicht, also musst du dir keinen Stress machen!<\/li>\n<\/ul>\n<p>Ursprung: Vom Backbuch <a href=\"https:\/\/www.tchibo.de\/buch-fruehlingsbacken-p400148139.html\" target=\"_blank\" rel=\"noopener noreferrer\">&#8222;Fr\u00fchlingsbacken&#8220;<\/a> etwas adaptiert, S. 11<\/p>\n<p><span class=\"sp_shortcode\">\t<div id=\"recipe\"><\/div>\r\n\t<div class=\"sp-recipe\" id=\"printthis\">\r\n\t\t\r\n\t\t<div class=\"recipe-overview\">\r\n\t\t\t\r\n\t\t\t<div class=\"recipe-image\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07688.jpg?w=1080&#038;ssl=1\">\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" onclick=\"jQuery('#printthis').print()\" class=\"sp-print\"><i class=\"fa fas fa-print\"><\/i> Print Recipe<\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t<div class=\"recipe-header\">\r\n\t\t\t\r\n\t\t\t\t<div class=\"recipe-title-header\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t<h2>Cremiger K\u00e4sekuchen mit Rhabarber- und Erdbeerso\u00dfe<\/h2>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"recipe-meta\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"meta-row\">\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"meta-row\">\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<i class=\"far fa-user\"><\/i>\t\t\t\t\t\t\r\n\t\t\t\t\t\t<span class=\"recipe-meta-item\">By Emma Friedrichs<\/span>\t\t\t\t\t\t<span class=\"separator\">&#8211;<\/span>\t\t\t\t\t\t<span class=\"recipe-meta-item\">Serves: Eine 20cm Springform mit hohem Rand<\/span>\t\t\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"meta-row\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t<i class=\"far fa-clock\"><\/i> \r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"recipe-meta-item\">Prep Time: 30min<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<span class=\"separator\">&#8211;<\/span>\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"recipe-meta-item\">Cooking Time: 1hr<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"sep-line\"><\/div>\r\n\t\t\t\t\t<div class=\"recipe-description\"><p>Dieser cremige K\u00e4sekuchen mit Rhabarber- und Erdbeerso\u00dfe hat einen Keksboden und wird in einer hohen 20er Springform zubereitet.<\/p><\/div>\r\n\t\t\t\t\t\t\t\r\n\t\t\t<\/div>\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\t<div class=\"recipe-ingredients\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t<h3 class=\"recipe-title\">Ingredients<\/h3>\r\n\t\t\t\r\n\t\t\t<ul>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span><b>Keksboden<\/b> <\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span>150 gr Butter<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span>300 gr Vollkornkekse (zu Coronazeiten gab es bei mir nur noch welche im Miniformat, aber immerhin gab es sie)<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span><\/br><\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span><b>K\u00e4sef\u00fcllung<\/b> <\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span>50 gr Speisest\u00e4rke<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span>100 gr Milch<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span>60 gr Sahne<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span>1 TL Vanilleextrakt, siehe <a href=\"http:\/\/jennyisbaking.com\/de\/2017\/02\/25\/how-to-make-vanilla-extract\/\" target=\"_blank\" rel=\"noopener noreferrer\">hier<\/a> wie man es selbst erstellt<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span>150 gr wei\u00dfer Zucker<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span>250 gr Quark (jede Fettstufe geht)<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span>150 gr Frischk\u00e4se<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span>200 gr Schmand<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span>3 Eier<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span>Saft einer halben Zitrone<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span><\/br><\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span><b>Rhabarber- und Erdbeerso\u00dfe<\/b> <\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span>200 gr Rhabarber (ca. 2 Stangen)<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span>100 gr wei\u00dfer Zucker<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span>150 gr Erdbeeren <\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><span>1 TL Vanilleextrakt, siehe <a href=\"http:\/\/jennyisbaking.com\/de\/2017\/02\/25\/how-to-make-vanilla-extract\/\" target=\"_blank\" rel=\"noopener noreferrer\">hier<\/a> wie man es selbst erstellt<\/span><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"recipe-method\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t<h3 class=\"recipe-title\">Instructions<\/h3>\r\n\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"step\">\r\n\t\t\t\t\t<span class=\"step-number\">1<\/span>\r\n\t\t\t\t\t<div class=\"step-content\">\r\n\t\t\t\t\t\t<p>F\u00fcr den <b>Keksboden<\/b> die Butter schmelzen. Derweil die Kekse entweder im Foodprozessor, in einem verschlossenen Gefrierbeutel mit einem Nudelholz oder im M\u00f6rser fein zerkleinern. Beides vermischen und in eine 20er Springform mit hohem Rand geben. Die H\u00e4lfte mit einem L\u00f6ffelr\u00fccken zun\u00e4chst am Rand gut festdr\u00fccken, dann den Rest auf dem Boden plattdr\u00fccken, das geht auch sehr gut mit einem Glasboden. Im K\u00fchlschrank ca. 20min oder l\u00e4nger festwerden lassen. <\/p>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"step\">\r\n\t\t\t\t\t<span class=\"step-number\">2<\/span>\r\n\t\t\t\t\t<div class=\"step-content\">\r\n\t\t\t\t\t\t<p>Derweil die <b>F\u00fcllung<\/b> vorbereiten. Dazu den Ofen auf 170 Grad vorheizen und die Speisest\u00e4rke in der Milch und Sahne in einer gro\u00dfen Sch\u00fcssel gut aufl\u00f6sen bis man keine Kl\u00fcmpchen mehr sieht. Dann Vanilleextrakt und Zucker per Schneebesen einr\u00fchren. <\/p>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"step\">\r\n\t\t\t\t\t<span class=\"step-number\">3<\/span>\r\n\t\t\t\t\t<div class=\"step-content\">\r\n\t\t\t\t\t\t<p>Quark, Frischk\u00e4se und Schmand einr\u00fchren, bis eine cremige Masse entsteht. Die Eier und Zitronensaft am Ende vorsichtig einr\u00fchren, dabei m\u00f6glichst wenig Luft einarbeiten. Auf den Keksboden verteilen, die Masse ist relativ d\u00fcnnfl\u00fcssig. <\/p>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"step\">\r\n\t\t\t\t\t<span class=\"step-number\">4<\/span>\r\n\t\t\t\t\t<div class=\"step-content\">\r\n\t\t\t\t\t\t<p>Den K\u00e4sekuchen ca. 55min-60 min auf mittlerer Schiene backen, er sollte nur leicht br\u00e4unen und kann gerne noch in der Mitte etwas wackeln. Bei ge\u00f6ffneter Ofent\u00fcr eine weitere Stunde ausk\u00fchlen, dann auf Raumtemperatur bringen und am Ende \u00fcber Nacht oder f\u00fcr einige Stunden in den K\u00fchlschrank. Aber selbst wenn es Risse gibt, nicht schlimm, wir machen ja die So\u00dfe dr\u00fcber!<\/p>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"step\">\r\n\t\t\t\t\t<span class=\"step-number\">5<\/span>\r\n\t\t\t\t\t<div class=\"step-content\">\r\n\t\t\t\t\t\t<p>F\u00fcr die <b>So\u00dfe<\/b> den Rhabarber waschen, sch\u00e4len und in ca. 2cm dicke Scheiben schneiden und zusammen mit dem Zucker auf mittlerer Hitze weich d\u00fcnsten, dabei gelegentlich umr\u00fchren. Die Erdbeeren waschen und in kleinere St\u00fcckchen schneiden und dazugeben, f\u00fcr zwei Minuten weiter d\u00fcnsten, dann Vanillextrakt hinzugeben. Abk\u00fchlen lassen. <\/p>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"step\">\r\n\t\t\t\t\t<span class=\"step-number\">6<\/span>\r\n\t\t\t\t\t<div class=\"step-content\">\r\n\t\t\t\t\t\t<p>Den Kuchen vorsichtig aus der Springform l\u00f6sen und mit der So\u00dfe servieren.<\/p>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t\r\n\t\t<script type=\"application\/ld+json\">\r\n\t\t\t{\r\n\t\t\t  \"@context\": \"http:\/\/schema.org\",\r\n\t\t\t  \"@type\": \"Recipe\",\r\n\t\t\t  \"url\": \"https:\/\/jennyisbaking.com\/de\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/\",\r\n\t\t\t  \"author\": {\r\n\t\t\t\t\"@type\": \"Thing\",\r\n\t\t\t\t\"name\": \"Emma Friedrichs\"\r\n\t\t\t  },\r\n\t\t\t  \"datePublished\": \"Freitag, der 27. M\u00e4rz 2020\",\r\n\t\t\t  \"cookTime\": \"P\",\r\n\t\t\t  \t\t\t  \"description\": \"Dieser cremige K\u00e4sekuchen mit Rhabarber- und Erdbeerso\u00dfe hat einen Keksboden und wird in einer hohen 20er Springform zubereitet.\",\r\n\t\t\t  \"image\": \"https:\/\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07688.jpg\",\r\n\t\t\t  \"recipeIngredient\": [\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"<b>Keksboden<\/b> \",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"150 gr Butter\",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"300 gr Vollkornkekse (zu Coronazeiten gab es bei mir nur noch welche im Miniformat, aber immerhin gab es sie)\",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"<\/br>\",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"<b>K\u00e4sef\u00fcllung<\/b> \",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"50 gr Speisest\u00e4rke\",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"100 gr Milch\",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"60 gr Sahne\",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"1 TL Vanilleextrakt, siehe <a href=\"http:\/\/jennyisbaking.com\/de\/2017\/02\/25\/how-to-make-vanilla-extract\/\" target=\"_blank\" rel=\"noopener noreferrer\">hier<\/a> wie man es selbst erstellt\",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"150 gr wei\u00dfer Zucker\",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"250 gr Quark (jede Fettstufe geht)\",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"150 gr Frischk\u00e4se\",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"200 gr Schmand\",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"3 Eier\",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"Saft einer halben Zitrone\",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"<\/br>\",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"<b>Rhabarber- und Erdbeerso\u00dfe<\/b> \",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"200 gr Rhabarber (ca. 2 Stangen)\",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"100 gr wei\u00dfer Zucker\",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"150 gr Erdbeeren \",\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\"1 TL Vanilleextrakt, siehe <a href=\"http:\/\/jennyisbaking.com\/de\/2017\/02\/25\/how-to-make-vanilla-extract\/\" target=\"_blank\" rel=\"noopener noreferrer\">hier<\/a> wie man es selbst erstellt\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t  ],\r\n\t\t\t  \"name\": \"Cremiger K\u00e4sekuchen mit Rhabarber- und Erdbeerso\u00dfe\",\r\n\t\t\t  \"nutrition\": {\r\n\t\t\t\t\"@type\": \"NutritionInformation\",\r\n\t\t\t\t\"calories\": \"\",\r\n\t\t\t\t\"carbohydrateContent\": \"\",\r\n\t\t\t\t\"cholesterolContent\": \"\",\r\n\t\t\t\t\"fatContent\": \"\",\r\n\t\t\t\t\"fiberContent\": \"\",\r\n\t\t\t\t\"proteinContent\": \"\",\r\n\t\t\t\t\"saturatedFatContent\": \"\",\r\n\t\t\t\t\"sodiumContent\": \"\",\r\n\t\t\t\t\"sugarContent\": \"\",\r\n\t\t\t\t\"transFatContent\": \"\",\r\n\t\t\t\t\"unsaturatedFatContent\": \"\"\r\n\t\t\t  },\r\n\t\t\t  \"prepTime\": \"PT30M\",\r\n\t\t\t  \"totalTime\": \"P\",\r\n\t\t\t  \"recipeCategory\":\"\",\r\n\t\t\t  \"recipeCuisine\":\"\",\r\n\t\t\t  \"keywords\": \"\",\t\t\t  \r\n\t\t\t  \"recipeInstructions\": [\r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"F\u00fcr den <b>Keksboden<\/b> die Butter schmelzen. Derweil die Kekse entweder im Foodprozessor, in einem verschlossenen Gefrierbeutel mit einem Nudelholz oder im M\u00f6rser fein zerkleinern. Beides vermischen und in eine 20er Springform mit hohem Rand geben. Die H\u00e4lfte mit einem L\u00f6ffelr\u00fccken zun\u00e4chst am Rand gut festdr\u00fccken, dann den Rest auf dem Boden plattdr\u00fccken, das geht auch sehr gut mit einem Glasboden. Im K\u00fchlschrank ca. 20min oder l\u00e4nger festwerden lassen. \",\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"Derweil die <b>F\u00fcllung<\/b> vorbereiten. Dazu den Ofen auf 170 Grad vorheizen und die Speisest\u00e4rke in der Milch und Sahne in einer gro\u00dfen Sch\u00fcssel gut aufl\u00f6sen bis man keine Kl\u00fcmpchen mehr sieht. Dann Vanilleextrakt und Zucker per Schneebesen einr\u00fchren. \",\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"Quark, Frischk\u00e4se und Schmand einr\u00fchren, bis eine cremige Masse entsteht. Die Eier und Zitronensaft am Ende vorsichtig einr\u00fchren, dabei m\u00f6glichst wenig Luft einarbeiten. Auf den Keksboden verteilen, die Masse ist relativ d\u00fcnnfl\u00fcssig. \",\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"Den K\u00e4sekuchen ca. 55min-60 min auf mittlerer Schiene backen, er sollte nur leicht br\u00e4unen und kann gerne noch in der Mitte etwas wackeln. Bei ge\u00f6ffneter Ofent\u00fcr eine weitere Stunde ausk\u00fchlen, dann auf Raumtemperatur bringen und am Ende \u00fcber Nacht oder f\u00fcr einige Stunden in den K\u00fchlschrank. Aber selbst wenn es Risse gibt, nicht schlimm, wir machen ja die So\u00dfe dr\u00fcber!\",\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"F\u00fcr die <b>So\u00dfe<\/b> den Rhabarber waschen, sch\u00e4len und in ca. 2cm dicke Scheiben schneiden und zusammen mit dem Zucker auf mittlerer Hitze weich d\u00fcnsten, dabei gelegentlich umr\u00fchren. Die Erdbeeren waschen und in kleinere St\u00fcckchen schneiden und dazugeben, f\u00fcr zwei Minuten weiter d\u00fcnsten, dann Vanillextrakt hinzugeben. Abk\u00fchlen lassen. \",\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"Den Kuchen vorsichtig aus der Springform l\u00f6sen und mit der So\u00dfe servieren.\"\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t  ],\r\n\t\t\t  \t\t\t  \"recipeYield\": \"Eine 20cm Springform mit hohem Rand\"\t\t\t  \t\t\t}\r\n\t\t<\/script>\r\n\t\t\r\n\t<\/div>\r\n\t<\/span><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07668.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"10162\" data-permalink=\"https:\/\/jennyisbaking.com\/de\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/dsc07668\/\" data-orig-file=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07668.jpg?fit=534%2C801&amp;ssl=1\" data-orig-size=\"534,801\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;Jennifer Warkentin&quot;,&quot;camera&quot;:&quot;ILCE-7&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1584725683&quot;,&quot;copyright&quot;:&quot;Jennifer Warkentin&quot;,&quot;focal_length&quot;:&quot;50&quot;,&quot;iso&quot;:&quot;640&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Das Backbuch Fr\u00fchlingsbacken von Tchibo\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07668.jpg?fit=534%2C801&amp;ssl=1\" class=\"aligncenter size-full wp-image-10162\" src=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07668.jpg?resize=534%2C801&#038;ssl=1\" alt=\"Das Backbuch Fr\u00fchlingsbacken von Tchibo\" width=\"534\" height=\"801\" srcset=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07668.jpg?w=534&amp;ssl=1 534w, https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07668.jpg?resize=200%2C300&amp;ssl=1 200w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" \/><\/a><del>So, und nun zu dem Gewinnspiel. Ich verlose gleich zwei Mal dieses wundersch\u00f6ne Backbuch. Was dich erwartet?<\/del><\/p>\n<ul>\n<li><del>40 Rezepte auf 94 Seiten zum Thema Fr\u00fchling, viele davon mit Fr\u00fcchten, jedes Rezept mit Bild (finde ich pers\u00f6nlich immer wichtig), Emma selbst hat auf ihrem Blog die <a href=\"https:\/\/emmaslieblingsstuecke.com\/2020\/03\/17\/himbeertarte-mit-weisser-schokolade-ohne-backen\/\" target=\"_blank\" rel=\"noopener noreferrer\">Himbeer-Tarte mit wei\u00dfer Schokolade<\/a> ver\u00f6ffentlicht und die <a href=\"https:\/\/emmaslieblingsstuecke.com\/2020\/03\/25\/einfaches-rezept-fuer-rhabarber-muffins-aus-meinem-neuen-backbuch\/\" target=\"_blank\" rel=\"noopener noreferrer\">Rhabarber-Muffins,<\/a> dann hast du schon mal einen Eindruck<\/del><\/li>\n<li><del>Aufgeteilt in die Kategorien Kuchen, Torten, Kleingeb\u00e4ck, Tartes und Pies, Cupcakes und Muffins<\/del><\/li>\n<li><del>Bei Tchibo erh\u00e4ltlich f\u00fcr 9,99 EUR<\/del><\/li>\n<li><del>Alle Rezepte entwickelt, zubereitet und fotografiert von der tollen Emma von <a href=\"https:\/\/emmaslieblingsstuecke.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Emmas Lieblingsst\u00fccke<\/a> (schau unbedingt auf ihren Blog vorbei, sie hat viele wundervolle Rezepte im Angebot!)<\/del><\/li>\n<li><del>\u00dcbrigens gibt es dieses Buch nur sechs Wochen bei Tchibo, wollte ich nur am Rande erw\u00e4hnen&#8230;<\/del><\/li>\n<\/ul>\n<p><del>Was du tun musst, um in den Lostopf zu h\u00fcpfen?<\/del><\/p>\n<ul>\n<li><del>Mir hier verraten was dein <strong>Lieblingsbackrezept im Fr\u00fchling<\/strong> ist. Alle Kommentare bis zum 30.03.2020 23.59 Uhr sind g\u00fcltig.<\/del><\/li>\n<li><del>Teilnehmen k\u00f6nnen<strong> alle Leser aus der Europ\u00e4ischen Union, die mindestens 18 Jahre alt sind<\/strong>. Und zwar nur einmal mit einem g\u00fcltigen Kommentar auf diesen Beitrag, Mehrfachteilnahmen werden gel\u00f6scht.<\/del><\/li>\n<li><del>F\u00fcr technische Schwierigkeiten beim Absenden des Teilnahmekommentars bin ich nicht verantwortlich.<\/del><\/li>\n<li><del>Die Ermittlung der zwei Gewinner erfolgt per <strong>Zufallsverfahren<\/strong>.<\/del><\/li>\n<li><del>Eine <strong>g\u00fcltige Email-Adresse<\/strong> beim Kommentieren ist notwendig, damit die Gewinner im Fall des Gewinns informiert werden k\u00f6nnen.<\/del><\/li>\n<li><del>Die personenbezogenen Daten der Teilnehmenden werden gem\u00e4\u00df Art. 6 Abs. 1 lit. f DSGVO in dem Interesse verarbeitet, die Gewinnerinnen und Gewinner zu ermitteln und die Gewinnaussch\u00fcttung abzuwickeln.<\/del><\/li>\n<li><del>Die angeschriebenen Gewinner erhalten von mir eine E-Mail und werden um die Postadresse zwecks Gewinnversandes gebeten.<\/del><\/li>\n<\/ul>\n<p>Das Gewinnspiel wurde beendet, Gewinnner sind Chris und Kyr, sie wurden beide benachrichtigt.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07708-1.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"10161\" data-permalink=\"https:\/\/jennyisbaking.com\/de\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/dsc07708-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07708-1.jpg?fit=534%2C801&amp;ssl=1\" data-orig-size=\"534,801\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;Jennifer Warkentin&quot;,&quot;camera&quot;:&quot;ILCE-7&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1584727568&quot;,&quot;copyright&quot;:&quot;Jennifer Warkentin&quot;,&quot;focal_length&quot;:&quot;50&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Cremiger K\u00e4sekuchen mit Rhabarber- und Erdbeerso\u00dfe\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07708-1.jpg?fit=534%2C801&amp;ssl=1\" class=\"aligncenter size-full wp-image-10161\" src=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07708-1.jpg?resize=534%2C801&#038;ssl=1\" alt=\"Cremiger K\u00e4sekuchen mit Rhabarber- und Erdbeerso\u00dfe\" width=\"534\" height=\"801\" srcset=\"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07708-1.jpg?w=534&amp;ssl=1 534w, https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07708-1.jpg?resize=200%2C300&amp;ssl=1 200w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Leider ist der Eintrag nur auf English verf\u00fcgbar.<\/p>\n","protected":false},"author":1,"featured_media":10158,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,6,416,922,380,925,555],"tags":[366,1450,48,49,704,68,1451,392,151,150,705,108,109],"class_list":["post-10156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cakes","category-easter","category-fruhling","category-german-recipes","category-kuchen","category-mothers-day","category-ostern","tag-cheesecake","tag-cookie-crust","tag-erdbeer","tag-erdbeeren","tag-fruhling","tag-kaesekuchen","tag-keksboden","tag-quark","tag-rhabarber","tag-rhubarb","tag-spring","tag-strawberries","tag-strawberry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der cremigste Rhabarber-Erdbeer-K\u00e4sekuchen - Jenny is baking<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jennyisbaking.com\/de\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der cremigste Rhabarber-Erdbeer-K\u00e4sekuchen - Jenny is baking\" \/>\n<meta property=\"og:description\" content=\"Leider ist der Eintrag nur auf English verf\u00fcgbar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jennyisbaking.com\/de\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/\" \/>\n<meta property=\"og:site_name\" content=\"Jenny is baking\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jennyisbaking\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jennyisbaking\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-27T06:00:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-12T17:12:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07688.jpg?fit=534%2C801&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"534\" \/>\n\t<meta property=\"og:image:height\" content=\"801\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jenny\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jenny\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/2020\\\/03\\\/27\\\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/2020\\\/03\\\/27\\\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\\\/\"},\"author\":{\"name\":\"Jenny\",\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/#\\\/schema\\\/person\\\/28a46859582cac5ac1ef7e065a17f77b\"},\"headline\":\"Der cremigste Rhabarber-Erdbeer-K\u00e4sekuchen\",\"datePublished\":\"2020-03-27T06:00:40+00:00\",\"dateModified\":\"2020-05-12T17:12:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/2020\\\/03\\\/27\\\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\\\/\"},\"wordCount\":1393,\"commentCount\":55,\"image\":{\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/2020\\\/03\\\/27\\\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/jennyisbaking.com\\\/wp-1c174-content\\\/uploads\\\/2020\\\/03\\\/DSC07688.jpg?fit=534%2C801&ssl=1\",\"keywords\":[\"Cheesecake\",\"cookie crust\",\"Erdbeer\",\"Erdbeeren\",\"fr\u00fchling\",\"K\u00e4sekuchen\",\"keksboden\",\"Quark\",\"Rhabarber\",\"rhubarb\",\"spring\",\"strawberries\",\"strawberry\"],\"articleSection\":[\"Cakes\",\"Easter\",\"Fr\u00fchling\",\"German Recipes\",\"Kuchen\",\"Mother's Day\",\"Ostern\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jennyisbaking.com\\\/2020\\\/03\\\/27\\\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/2020\\\/03\\\/27\\\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\\\/\",\"url\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/2020\\\/03\\\/27\\\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\\\/\",\"name\":\"Der cremigste Rhabarber-Erdbeer-K\u00e4sekuchen - Jenny is baking\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/2020\\\/03\\\/27\\\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/2020\\\/03\\\/27\\\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/jennyisbaking.com\\\/wp-1c174-content\\\/uploads\\\/2020\\\/03\\\/DSC07688.jpg?fit=534%2C801&ssl=1\",\"datePublished\":\"2020-03-27T06:00:40+00:00\",\"dateModified\":\"2020-05-12T17:12:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/#\\\/schema\\\/person\\\/28a46859582cac5ac1ef7e065a17f77b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/2020\\\/03\\\/27\\\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/2020\\\/03\\\/27\\\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/2020\\\/03\\\/27\\\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/jennyisbaking.com\\\/wp-1c174-content\\\/uploads\\\/2020\\\/03\\\/DSC07688.jpg?fit=534%2C801&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/jennyisbaking.com\\\/wp-1c174-content\\\/uploads\\\/2020\\\/03\\\/DSC07688.jpg?fit=534%2C801&ssl=1\",\"width\":534,\"height\":801,\"caption\":\"Cremiger K\u00e4sekuchen mit Rhabarber- und Erdbeerso\u00dfe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/2020\\\/03\\\/27\\\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Creamy Cheesecake with Rhubarb and Strawberry Sauce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/\",\"name\":\"Jenny is baking\",\"description\":\"Backrezepte aus Nord- und S\u00fcdamerika\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/#\\\/schema\\\/person\\\/28a46859582cac5ac1ef7e065a17f77b\",\"name\":\"Jenny\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23e81660a6279fbe7db0db01e9985036a8488f0100c3985867731ba2b4348089?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23e81660a6279fbe7db0db01e9985036a8488f0100c3985867731ba2b4348089?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23e81660a6279fbe7db0db01e9985036a8488f0100c3985867731ba2b4348089?s=96&d=mm&r=g\",\"caption\":\"Jenny\"},\"description\":\"Hi, ich hei\u00dfe Jenny, geb\u00fcrtig in Uruguay, als Kind in USA gelebt, nach dem Abi in Kanada und mit einem Kolumbianer verheiratet. Ich wohne im Moment in M\u00fcnchen, S\u00fcddeutschland. Auf meinem Blog finden sich meist s\u00fc\u00dfe Rezepte. Ich mag normalerweise einfache Sachen, die schnell gemacht sind, aber gleichzeitig was hermachen. Manchmal packt mich auch der Ehrgeiz und ich wage mich an kompliziertere Torten. Schau dir im Men\u00fc \u201eAlle Rezepte\u201c an f\u00fcr weitere Inspiration.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jennyisbaking\\\/\",\"https:\\\/\\\/www.pinterest.de\\\/jennyisbaking\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der cremigste Rhabarber-Erdbeer-K\u00e4sekuchen - Jenny is baking","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jennyisbaking.com\/de\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/","og_locale":"de_DE","og_type":"article","og_title":"Der cremigste Rhabarber-Erdbeer-K\u00e4sekuchen - Jenny is baking","og_description":"Leider ist der Eintrag nur auf English verf\u00fcgbar.","og_url":"https:\/\/jennyisbaking.com\/de\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/","og_site_name":"Jenny is baking","article_publisher":"https:\/\/www.facebook.com\/jennyisbaking\/","article_author":"https:\/\/www.facebook.com\/jennyisbaking\/","article_published_time":"2020-03-27T06:00:40+00:00","article_modified_time":"2020-05-12T17:12:36+00:00","og_image":[{"width":534,"height":801,"url":"https:\/\/i1.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07688.jpg?fit=534%2C801&ssl=1","type":"image\/jpeg"}],"author":"Jenny","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Jenny","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jennyisbaking.com\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/#article","isPartOf":{"@id":"https:\/\/jennyisbaking.com\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/"},"author":{"name":"Jenny","@id":"https:\/\/jennyisbaking.com\/#\/schema\/person\/28a46859582cac5ac1ef7e065a17f77b"},"headline":"Der cremigste Rhabarber-Erdbeer-K\u00e4sekuchen","datePublished":"2020-03-27T06:00:40+00:00","dateModified":"2020-05-12T17:12:36+00:00","mainEntityOfPage":{"@id":"https:\/\/jennyisbaking.com\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/"},"wordCount":1393,"commentCount":55,"image":{"@id":"https:\/\/jennyisbaking.com\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07688.jpg?fit=534%2C801&ssl=1","keywords":["Cheesecake","cookie crust","Erdbeer","Erdbeeren","fr\u00fchling","K\u00e4sekuchen","keksboden","Quark","Rhabarber","rhubarb","spring","strawberries","strawberry"],"articleSection":["Cakes","Easter","Fr\u00fchling","German Recipes","Kuchen","Mother's Day","Ostern"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jennyisbaking.com\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jennyisbaking.com\/de\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/","url":"https:\/\/jennyisbaking.com\/de\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/","name":"Der cremigste Rhabarber-Erdbeer-K\u00e4sekuchen - Jenny is baking","isPartOf":{"@id":"https:\/\/jennyisbaking.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jennyisbaking.com\/de\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/#primaryimage"},"image":{"@id":"https:\/\/jennyisbaking.com\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07688.jpg?fit=534%2C801&ssl=1","datePublished":"2020-03-27T06:00:40+00:00","dateModified":"2020-05-12T17:12:36+00:00","author":{"@id":"https:\/\/jennyisbaking.com\/#\/schema\/person\/28a46859582cac5ac1ef7e065a17f77b"},"breadcrumb":{"@id":"https:\/\/jennyisbaking.com\/de\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/jennyisbaking.com\/de\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/"]]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jennyisbaking.com\/de\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/#primaryimage","url":"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07688.jpg?fit=534%2C801&ssl=1","contentUrl":"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07688.jpg?fit=534%2C801&ssl=1","width":534,"height":801,"caption":"Cremiger K\u00e4sekuchen mit Rhabarber- und Erdbeerso\u00dfe"},{"@type":"BreadcrumbList","@id":"https:\/\/jennyisbaking.com\/de\/2020\/03\/27\/creamy-cheesecake-with-rhubarb-and-strawberry-sauce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/jennyisbaking.com\/de\/"},{"@type":"ListItem","position":2,"name":"Creamy Cheesecake with Rhubarb and Strawberry Sauce"}]},{"@type":"WebSite","@id":"https:\/\/jennyisbaking.com\/de\/#website","url":"https:\/\/jennyisbaking.com\/de\/","name":"Jenny is baking","description":"Backrezepte aus Nord- und S\u00fcdamerika","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jennyisbaking.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/jennyisbaking.com\/#\/schema\/person\/28a46859582cac5ac1ef7e065a17f77b","name":"Jenny","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/23e81660a6279fbe7db0db01e9985036a8488f0100c3985867731ba2b4348089?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23e81660a6279fbe7db0db01e9985036a8488f0100c3985867731ba2b4348089?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23e81660a6279fbe7db0db01e9985036a8488f0100c3985867731ba2b4348089?s=96&d=mm&r=g","caption":"Jenny"},"description":"Hi, ich hei\u00dfe Jenny, geb\u00fcrtig in Uruguay, als Kind in USA gelebt, nach dem Abi in Kanada und mit einem Kolumbianer verheiratet. Ich wohne im Moment in M\u00fcnchen, S\u00fcddeutschland. Auf meinem Blog finden sich meist s\u00fc\u00dfe Rezepte. Ich mag normalerweise einfache Sachen, die schnell gemacht sind, aber gleichzeitig was hermachen. Manchmal packt mich auch der Ehrgeiz und ich wage mich an kompliziertere Torten. Schau dir im Men\u00fc \u201eAlle Rezepte\u201c an f\u00fcr weitere Inspiration.","sameAs":["https:\/\/www.facebook.com\/jennyisbaking\/","https:\/\/www.pinterest.de\/jennyisbaking\/"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2020\/03\/DSC07688.jpg?fit=534%2C801&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8MAhl-2DO","jetpack-related-posts":[{"id":8512,"url":"https:\/\/jennyisbaking.com\/de\/2019\/05\/03\/creamy-german-cheesecake-with-strawberries\/","url_meta":{"origin":10156,"position":0},"title":"Der cremigste K\u00e4sekuchen mit Erdbeeren","author":"Jenny","date":"Freitag, der  3. Mai 2019","format":false,"excerpt":"Heute habe ich hammerm\u00e4\u00dfig cremigen K\u00e4sekuchen mitgebracht, der mit ganz viel Erdbeeren daherkommt. Ihr wisst ja, ich liebe fruchtige Kuchen und da musste eben auch dieser K\u00e4sekuchen dran glauben und hat Erdbeeren verschrieben bekommen, so ganz kahl wollte ich nicht. Aber auch pur ist der K\u00e4sekuchen eine Wucht, er ist\u2026","rel":"","context":"In &quot;Cakes&quot;","block_context":{"text":"Cakes","link":"https:\/\/jennyisbaking.com\/de\/category\/cakes\/"},"img":{"alt_text":"K\u00e4sekuchen","src":"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2024\/04\/Kaesekuchen-mit-Erdbeeren-1.jpg?fit=534%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2024\/04\/Kaesekuchen-mit-Erdbeeren-1.jpg?fit=534%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2024\/04\/Kaesekuchen-mit-Erdbeeren-1.jpg?fit=534%2C801&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":14428,"url":"https:\/\/jennyisbaking.com\/de\/2023\/04\/06\/20-rezeptideen-zu-ostern\/","url_meta":{"origin":10156,"position":1},"title":"20 Rezeptideen zu Ostern","author":"Jenny","date":"Donnerstag, der  6. April 2023","format":false,"excerpt":"Du suchst noch Ideen f\u00fcr Ostern? Hier habe ich dir 20 Rezepte zusammengefasst, sch\u00f6n gegliedert nach Hefeteig, Fr\u00fchst\u00fcck\/Brunch, Cupcakes und Ostertorten. Ich halte mich kurz, frohe Ostern, genie\u00df den Fr\u00fchliing, die Hoffnung und W\u00e4rme! 1. Hefeteig Der beste Hefezopf \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Traditionelles Hefegeb\u00e4ck aus\u2026","rel":"","context":"In &quot;Easter&quot;","block_context":{"text":"Easter","link":"https:\/\/jennyisbaking.com\/de\/category\/easter\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2023\/04\/Ostertorte.jpg?fit=534%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2023\/04\/Ostertorte.jpg?fit=534%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2023\/04\/Ostertorte.jpg?fit=534%2C801&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":11837,"url":"https:\/\/jennyisbaking.com\/de\/2021\/03\/26\/rezeptideen-zu-ostern\/","url_meta":{"origin":10156,"position":2},"title":"Rezeptideen f\u00fcr Ostern","author":"Jenny","date":"Freitag, der 26. M\u00e4rz 2021","format":false,"excerpt":"Die brauchst Inspiration und Rezepte f\u00fcr Ostern? Hier gibt es alles f\u00fcrs Fr\u00fchst\u00fcck oder den Brunch, aber auch Cupcakes und coole Ostertorten.","rel":"","context":"In &quot;Easter&quot;","block_context":{"text":"Easter","link":"https:\/\/jennyisbaking.com\/de\/category\/easter\/"},"img":{"alt_text":"Oster-Rezeptideen","src":"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2021\/03\/Oster-Rezeptideen.jpg?fit=534%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2021\/03\/Oster-Rezeptideen.jpg?fit=534%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2021\/03\/Oster-Rezeptideen.jpg?fit=534%2C801&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":16363,"url":"https:\/\/jennyisbaking.com\/de\/2024\/04\/30\/rhabarber-erdbeer-crostata\/","url_meta":{"origin":10156,"position":3},"title":"Rhabarber-Erdbeer-Crostata","author":"Jenny","date":"Dienstag, der 30. April 2024","format":false,"excerpt":"Heute gibt es Rhabarber-Erdbeer-Crostata oder Rhabarber-Erdbeer-Galette. Das ist die rustikale Cousine des Rhabarber-Pies oder einer Rhabarber-Tarte, man rollt den rund Teig aus, legt das Obst mittig hinein und klappt den Teigrand einfach zur Mitte hin um. Nichts gro\u00df mit Gittermuster, dekorieren oder flechten, das geht schneller und einfacher. Da hatte\u2026","rel":"","context":"In &quot;Fr\u00fchling&quot;","block_context":{"text":"Fr\u00fchling","link":"https:\/\/jennyisbaking.com\/de\/category\/fruhling\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2024\/04\/Rhabarber-Erdbeer-Crostata-1.jpg?fit=534%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2024\/04\/Rhabarber-Erdbeer-Crostata-1.jpg?fit=534%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2024\/04\/Rhabarber-Erdbeer-Crostata-1.jpg?fit=534%2C801&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":10382,"url":"https:\/\/jennyisbaking.com\/de\/2024\/05\/10\/15-rezepte-mit-erdbeeren\/","url_meta":{"origin":10156,"position":4},"title":"Meine sechzehn liebsten Rezepte mit Erdbeeren","author":"Jenny","date":"Freitag, der 10. Mai 2024","format":false,"excerpt":"Gibt es eigentlich irgendjemanden auf der Welt, der\/die nicht Erdbeeren in irgendeiner Form liebt? Ich zumindest liebe Erdbeeren und dachte mir, ich stelle euch hier mal meine sechzehn Lieblinge vor. Egal, ob im Kuchen, zum Fr\u00fchst\u00fcck, Macarons oder auch Getr\u00e4nk, Erdbeeren sind einfach mega lecker. Und jetzt, wo wir langsam\u2026","rel":"","context":"In &quot;Cakes&quot;","block_context":{"text":"Cakes","link":"https:\/\/jennyisbaking.com\/de\/category\/cakes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2024\/04\/Erdbeeren-auf-dem_Feld.jpg?fit=534%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2024\/04\/Erdbeeren-auf-dem_Feld.jpg?fit=534%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2024\/04\/Erdbeeren-auf-dem_Feld.jpg?fit=534%2C801&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":17749,"url":"https:\/\/jennyisbaking.com\/de\/2025\/06\/06\/klassischer-deutscher-kasekuchen-von-oma\/","url_meta":{"origin":10156,"position":5},"title":"K\u00e4sekuchen ohne Boden nach Omas Rezept","author":"Jenny","date":"Freitag, der  6. Juni 2025","format":false,"excerpt":"Meine Oma war eine begnadete K\u00f6chin und zauberte die sch\u00f6nsten Kuchen. Ich habe von ihr ein Rezeptbuch vermacht bekommen nachdem sie gestorben ist, das ich hoch in Ehren halte. Heute stelle ich einen K\u00e4sekuchen vor, den ich in ihrem Rezeptbuch gefunden habe. Sie nennt ihn \"Quarckkuchen\". Bei dem Rezept gibt\u2026","rel":"","context":"In &quot;All Seasons&quot;","block_context":{"text":"All Seasons","link":"https:\/\/jennyisbaking.com\/de\/category\/all-seasons\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2025\/02\/Kasekuchen-ohne-Boden.jpg?fit=534%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2025\/02\/Kasekuchen-ohne-Boden.jpg?fit=534%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/jennyisbaking.com\/wp-1c174-content\/uploads\/2025\/02\/Kasekuchen-ohne-Boden.jpg?fit=534%2C801&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/jennyisbaking.com\/de\/wp-json\/wp\/v2\/posts\/10156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jennyisbaking.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jennyisbaking.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jennyisbaking.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jennyisbaking.com\/de\/wp-json\/wp\/v2\/comments?post=10156"}],"version-history":[{"count":20,"href":"https:\/\/jennyisbaking.com\/de\/wp-json\/wp\/v2\/posts\/10156\/revisions"}],"predecessor-version":[{"id":10388,"href":"https:\/\/jennyisbaking.com\/de\/wp-json\/wp\/v2\/posts\/10156\/revisions\/10388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jennyisbaking.com\/de\/wp-json\/wp\/v2\/media\/10158"}],"wp:attachment":[{"href":"https:\/\/jennyisbaking.com\/de\/wp-json\/wp\/v2\/media?parent=10156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jennyisbaking.com\/de\/wp-json\/wp\/v2\/categories?post=10156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jennyisbaking.com\/de\/wp-json\/wp\/v2\/tags?post=10156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}