{"id":2832,"count":1,"description":"","link":"https:\/\/jennyisbaking.com\/de\/tag\/quitten-kase\/","name":"quitten k\u00e4se","slug":"quitten-kase","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>quitten k\u00e4se Archives - Jenny is baking<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jennyisbaking.com\/de\/tag\/quitten-kase\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"quitten k\u00e4se Archives - Jenny is baking\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jennyisbaking.com\/de\/tag\/quitten-kase\/\" \/>\n<meta property=\"og:site_name\" content=\"Jenny is baking\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/tag\\\/quitten-kase\\\/\",\"url\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/tag\\\/quitten-kase\\\/\",\"name\":\"quitten k\u00e4se Archives - Jenny is baking\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/tag\\\/quitten-kase\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/tag\\\/quitten-kase\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"quitten k\u00e4se\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/\",\"name\":\"Jenny is baking\",\"description\":\"Backrezepte aus Nord- und S\u00fcdamerika\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jennyisbaking.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"quitten k\u00e4se Archives - Jenny is baking","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jennyisbaking.com\/de\/tag\/quitten-kase\/","og_locale":"de_DE","og_type":"article","og_title":"quitten k\u00e4se Archives - Jenny is baking","og_url":"https:\/\/jennyisbaking.com\/de\/tag\/quitten-kase\/","og_site_name":"Jenny is baking","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/jennyisbaking.com\/de\/tag\/quitten-kase\/","url":"https:\/\/jennyisbaking.com\/de\/tag\/quitten-kase\/","name":"quitten k\u00e4se Archives - Jenny is baking","isPartOf":{"@id":"https:\/\/jennyisbaking.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/jennyisbaking.com\/de\/tag\/quitten-kase\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/jennyisbaking.com\/de\/tag\/quitten-kase\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/jennyisbaking.com\/de\/"},{"@type":"ListItem","position":2,"name":"quitten k\u00e4se"}]},{"@type":"WebSite","@id":"https:\/\/jennyisbaking.com\/de\/#website","url":"https:\/\/jennyisbaking.com\/de\/","name":"Jenny is baking","description":"Backrezepte aus Nord- und S\u00fcdamerika","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jennyisbaking.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/jennyisbaking.com\/de\/wp-json\/wp\/v2\/tags\/2832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jennyisbaking.com\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jennyisbaking.com\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jennyisbaking.com\/de\/wp-json\/wp\/v2\/posts?tags=2832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}